{"id":371464,"date":"2026-04-06T23:17:37","date_gmt":"2026-04-06T22:17:37","guid":{"rendered":"https:\/\/monster-bite.madwise-labs.si\/product\/izdelek-6\/"},"modified":"2026-06-25T18:18:58","modified_gmt":"2026-06-25T17:18:58","slug":"perla-in-gomma-cygnet-6mm","status":"publish","type":"product","link":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/","title":{"rendered":"CYGNET RUBBER BEAD 6mm"},"content":{"rendered":"<p><strong>PERLA IN GOMMA CYGNET 6mm<\/strong><\/p>\n<p>Migliora le tue montature da pesca con la PERLA IN GOMMA CYGNET 6mm, progettata per durabilit\u00e0 e funzionalit\u00e0. Queste perle sono ideali per:<\/p>\n<ul>\n<li><strong>Montature Elicottero e Run Rig:<\/strong> Proteggono i nodi e garantiscono un movimento fluido della lenza.<\/li>\n<li><strong>Terminali o Tubazioni:<\/strong> Facilitano le configurazioni elicottero per montature versatili.<\/li>\n<li><strong>Montature Run Rig o con Galleggiante Segnalatore:<\/strong> Salvaguardano i nodi e mantengono prestazioni ottimali.<\/li>\n<\/ul>\n<p>Caratterizzate da un colore mimetico, queste perle si integrano perfettamente nel fondale del lago, riducendo la visibilit\u00e0 ai pesci. La loro morbida costruzione in gomma offre una calzata sicura senza danneggiare la lenza. Disponibili in confezioni da 10, la PERLA IN GOMMA CYGNET 6mm \u00e8 un&#8217;aggiunta indispensabile alla tua cassetta da pesca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PERLA IN GOMMA CYGNET 6mm Migliora le tue montature da pesca con la PERLA IN GOMMA CYGNET 6mm, progettata per durabilit\u00e0 e funzionalit\u00e0. Queste perle sono ideali per: Montature Elicottero e Run Rig: Proteggono i nodi e garantiscono un movimento fluido della lenza. Terminali o Tubazioni: Facilitano le configurazioni elicottero per montature versatili. Montature Run &hellip; <a href=\"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/\">Continued<\/a><\/p>\n","protected":false},"featured_media":371453,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[51123,58225,60801,51284],"product_tag":[],"berocket_brand":[6388],"class_list":["post-371464","product","type-product","status-publish","has-post-thumbnail","product_cat-pesca-in-acqua-dolce","product_cat-accessori-per-montature","product_cat-componenti-per-rig","product_cat-carpfishing","berocket_brand-cygnet-it","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CYGNET RUBBER BEAD 6mm - Monster Bite<\/title>\n<meta name=\"description\" content=\"Perle in gomma 6mm resistenti per montature da pesca, con mimetizzazione e protezione nodi. Confezione da 10.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CYGNET RUBBER BEAD 6mm - Monster Bite\" \/>\n<meta property=\"og:description\" content=\"Perle in gomma 6mm resistenti per montature da pesca, con mimetizzazione e protezione nodi. Confezione da 10.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Monster Bite\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T17:18:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/monster-bite.madwise-labs.si\/wp-content\/uploads\/2026\/04\/bead2_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/\",\"url\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/\",\"name\":\"CYGNET RUBBER BEAD 6mm - Monster Bite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bead2_1.png\",\"datePublished\":\"2026-04-06T22:17:37+00:00\",\"dateModified\":\"2026-06-25T17:18:58+00:00\",\"description\":\"Perle in gomma 6mm resistenti per montature da pesca, con mimetizzazione e protezione nodi. Confezione da 10.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bead2_1.png\",\"contentUrl\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bead2_1.png\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/prodotto\\\/perla-in-gomma-cygnet-6mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CYGNET RUBBER BEAD 6mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/\",\"name\":\"Monster Bite\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/monster-bite.madwise-labs.si\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CYGNET RUBBER BEAD 6mm - Monster Bite","description":"Perle in gomma 6mm resistenti per montature da pesca, con mimetizzazione e protezione nodi. Confezione da 10.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"CYGNET RUBBER BEAD 6mm - Monster Bite","og_description":"Perle in gomma 6mm resistenti per montature da pesca, con mimetizzazione e protezione nodi. Confezione da 10.","og_url":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/","og_site_name":"Monster Bite","article_modified_time":"2026-06-25T17:18:58+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/monster-bite.madwise-labs.si\/wp-content\/uploads\/2026\/04\/bead2_1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/","url":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/","name":"CYGNET RUBBER BEAD 6mm - Monster Bite","isPartOf":{"@id":"https:\/\/monster-bite.madwise-labs.si\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/#primaryimage"},"image":{"@id":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/#primaryimage"},"thumbnailUrl":"https:\/\/monster-bite.madwise-labs.si\/wp-content\/uploads\/2026\/04\/bead2_1.png","datePublished":"2026-04-06T22:17:37+00:00","dateModified":"2026-06-25T17:18:58+00:00","description":"Perle in gomma 6mm resistenti per montature da pesca, con mimetizzazione e protezione nodi. Confezione da 10.","breadcrumb":{"@id":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/#primaryimage","url":"https:\/\/monster-bite.madwise-labs.si\/wp-content\/uploads\/2026\/04\/bead2_1.png","contentUrl":"https:\/\/monster-bite.madwise-labs.si\/wp-content\/uploads\/2026\/04\/bead2_1.png","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/monster-bite.madwise-labs.si\/it\/prodotto\/perla-in-gomma-cygnet-6mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/monster-bite.madwise-labs.si\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/monster-bite.madwise-labs.si\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"CYGNET RUBBER BEAD 6mm"}]},{"@type":"WebSite","@id":"https:\/\/monster-bite.madwise-labs.si\/it\/#website","url":"https:\/\/monster-bite.madwise-labs.si\/it\/","name":"Monster Bite","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monster-bite.madwise-labs.si\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/product\/371464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/media\/371453"}],"wp:attachment":[{"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/media?parent=371464"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/product_brand?post=371464"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/product_cat?post=371464"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/product_tag?post=371464"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/monster-bite.madwise-labs.si\/it\/wp-json\/wp\/v2\/berocket_brand?post=371464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}